{"id":4946,"date":"2021-10-21T09:05:42","date_gmt":"2021-10-21T07:05:42","guid":{"rendered":"https:\/\/kg-media.eu\/?p=4946"},"modified":"2025-03-07T11:21:08","modified_gmt":"2025-03-07T10:21:08","slug":"ga4-google-analytics-4-ist-da","status":"publish","type":"post","link":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/","title":{"rendered":"GA4 &#8211; Google Analytics 4 ist da"},"content":{"rendered":"<p><p>Google Analytics 4 (abgek\u00fcrzt: <strong>GA4<\/strong>) ist eine neue Generation von Google Analytics, die letztes Jahr (2020) eingef\u00fchrt wurde.<\/p>\n<p>Wir haben viele Fragen von unseren Kunden zu diesem Thema erhalten, daher m\u00f6chten wir diesen Artikel verwenden, um die wichtigsten Neuigkeiten zu GA4 zu erl\u00e4utern und <a href=\"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/#pitanjaiodgovori\">Antworten auf die eingegangenen Fragen<\/a> zu geben (weiter scrollen).<\/p>\n<p>Wenn wir weitere wichtige Fragen erhalten, werden wir sie diesem Artikel hinzuf\u00fcgen. Setzen Sie daher ein Lesezeichen f\u00fcr <a href=\"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/\" target=\"_blank\" rel=\"noopener\">diesen Link<\/a>, um sp\u00e4ter Referenzen zu diesem Thema zu haben.<\/p>\n<figure id=\"attachment_4875\" aria-describedby=\"caption-attachment-4875\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><a ref=\"magnificPopup\" href=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA_History-1-1024x333-1.gif\" class=\"fancybox\" ><img decoding=\"async\" class=\"wp-image-4875 size-full\" title=\"Chronologie der Einf\u00fchrung der Statistiksoftware von Google\" src=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA_History-1-1024x333-1.gif\" alt=\"kronologija statisti\u010dkih softwarea\" width=\"1024\" height=\"333\" \/><\/a><figcaption id=\"caption-attachment-4875\" class=\"wp-caption-text\">Chronologie der Einf\u00fchrung der Statistiksoftware von Google<\/figcaption><\/figure>\n<h2>GA4 zusammengefasst<\/h2>\n<p><a href=\"https:\/\/de.wikipedia.org\/wiki\/Datenschutz-Grundverordnung\" target=\"_blank\" rel=\"noopener\">DSGVO<\/a>, <a href=\"https:\/\/www.cookiebot.com\/de\/was-ist-ccpa\/\" target=\"_blank\" rel=\"noopener\">CCPA<\/a> und \u201eprivates Browsing\u201c haben sich darauf ausgewirkt, wie und welche Daten Cookies sammeln k\u00f6nnen. Google erwartet, dass das Tracking \u00fcber Cookies bald endet, und wenn das passiert, ist GA3 (Universal Analytics) tot. Wir wissen nicht, wann das passieren wird, aber immer mehr Internetbrowser setzen neue Einschr\u00e4nkungen f\u00fcr Cookies und im Laufe der Zeit wird GA3 \/ UA (aktuelle Version von Analytics = Universal Analytics) immer weniger Informationen erhalten.<\/p>\n<blockquote>\n<p>Aus diesem Grund empfehlen wir Ihnen, so schnell wie m\u00f6glich ein Google Analytics 4 (GA4)-Konto zu er\u00f6ffnen.<\/p>\n<\/blockquote>\n<p>Dies ist eine Investition in die Zukunft. Da GA4 mit <a href=\"https:\/\/de.wikipedia.org\/wiki\/Maschinelles_Lernen\" target=\"_blank\" rel=\"noopener\">maschinellem Lernen<\/a> arbeitet, ist es umso intelligenter \/ zuverl\u00e4ssiger \/ genauer, je mehr Daten es sammelt. Deshalb ist es wichtig, es jetzt zu implementieren, damit das System eine Datenbank generieren kann, w\u00e4hrend wir noch GA3 (Universal Analytics) verwenden k\u00f6nnen.<\/p>\n<p>Es ist auch wichtig zu beachten, dass sich GA4 nicht mehr in der <em>Betaphase<\/em> befindet. Einige Segmente werden noch hinzugef\u00fcgt und getestet, dies f\u00e4llt jedoch unter das \u00fcbliche Upgrade eines bestehenden Produkts.<\/p>\n<p>Kurz gesagt: Alle Analytics-Inhaber sollten GA4 jetzt implementieren, aber auch weiterhin GA3 verwenden.<\/p>\n \n\t\t<button id=\"btn_contact_form\" class=\"btn btn-primary btn-lg btn--cta \" type=\"button\" data-toggle=\"modal\" data-target=\"#cfModal\">Kontaktieren Sie uns!<span style=\"font-weight: 400;\"><\/button>\n<\/span><\/p>\n<h2>GA4: Vorteile und Nachteile<\/h2>\n<h3>Vorteile von GA4 gegen\u00fcber GA3<\/h3>\n<ul style=\"list-style-type: circle;\">\n<li>GA4 kontrolliert, wie Daten gesammelt, verarbeitet und gespeichert werden. Die Anonymisierung der IP-Adresse ist standardm\u00e4\u00dfig aktiviert;<\/li>\n<li>Es funktioniert auch ohne Cookies;<\/li>\n<li>Die automatische Ereignisverfolgung ist aktiviert. &#8222;Erweiterte&#8220; Ziele wie Brosch\u00fcren-Downloads, Scrollen, Videoanzeige oder Anklicken externer Links erforderten bisher eine zus\u00e4tzliche Konfiguration durch den Google Tag Manager (GTM);<\/li>\n<li>Metriken von Universal Analytics wie die Absprungrate wurden durch eine Engagement-Rate ersetzt. Dies liegt daran, dass GA4 Daten durch Ereignisse sammelt, nicht durch Sitzungen. Vergleich aus der Praxis: Verl\u00e4sst ein Nutzer die Seite, auf die er gelangt ist (z. B. einen <a href=\"https:\/\/kg-media.eu\/de\/blog\/performance-marketing-diamonds-cee-2018-wettbewerb-in-warschau\/\" target=\"_blank\" rel=\"noopener\">Blog-Artikel<\/a>), ohne weiter im Web zu surfen und hat diese zuvor vollst\u00e4ndig gelesen, w\u00fcrde GA3 einen solchen Besuch als Bounce (Absprung) verbuchen (allgemein als negatives Ph\u00e4nomen wahrgenommen), w\u00e4hrend es mit GA4 als positives Engagement anerkannt wird. Zus\u00e4tzlich zu den oben genannten bietet GA4 noch viele neue Metriken;<\/li>\n<li>GA4 wird von einer k\u00fcnstlichen Intelligenz (KI) angetrieben, sodass diese in ihrer Benutzeroberfl\u00e4che vorschl\u00e4gt, welche Marketing-\u201eEntscheidungen\u201c getroffen werden m\u00fcssen, um den ROI zu verbessern. Google behauptet, die M\u00f6glichkeit zu haben, Nutzer zu identifizieren, die eher kaufen\/konvertieren und so ein \u201eintelligentes Publikum\u201c zu schaffen;<\/li>\n<li>Werbetreibende k\u00f6nnen durch Besuche von Benutzern sowohl der Website als auch der App eine Zielgruppe (Liste) aufbauen. Die Liste wird automatisch auf allen Plattformen synchronisiert; Wenn ein Benutzer beispielsweise durch den Besuch einer Website auf die Liste gelangt ist und dann \u00fcber die App konvertiert (einen Kauf get\u00e4tigt hat), wird dies vom System erkannt und aus der weiteren Remarketing-Liste entfernt. Genauso verh\u00e4lt es sich mit YouTube-Rezensionen und -Aktionen, die ab sofort auch auf allen Plattformen synchronisiert werden.<\/li>\n<\/ul>\n<h3>Nachteile von GA4 gegen\u00fcber GA3<\/h3>\n<ul style=\"list-style-type: square;\">\n<li>Anfangs gibt es keine Daten und sie k\u00f6nnen nicht aus GA3 importiert werden. Sobald ein neues GA4-Konto er\u00f6ffnet wird, werden die Daten von Grund auf neu erfasst. Deshalb ist es wichtig, jetzt eine Datenbank zu erstellen.<\/li>\n<li>Das Design der GA4-Schnittstelle selbst unterscheidet sich deutlich von der des GA3, sodass die Anpassung viel Zeit in Anspruch nimmt. Es gibt viele neue Metriken, die einige alte ersetzt haben, an die Sie sich auch gew\u00f6hnen m\u00fcssen.<\/li>\n<\/ul>\n \n\t\t<button id=\"btn_contact_form\" class=\"btn btn-primary btn-lg btn--cta \" type=\"button\" data-toggle=\"modal\" data-target=\"#cfModal\">Kontaktieren Sie uns!<span style=\"font-weight: 400;\"><\/button>\n<\/span><\/p>\n<h2><a id=\"pitanjaiodgovori\"><\/a>GA4 &#x1f449; <span style=\"color: #ff0000;\">Fragen<\/span> und <span style=\"color: #339966;\">Antworten<\/span><\/h2>\n<p><strong>Was kann schief gehen?<\/strong><\/p>\n<p><span style=\"color: #ff0000;\">F: Was kann nach der Implementierung von GA4 schief gehen? Wenn Google aus irgendeinem Grund beschlie\u00dft, GA4 einzustellen, kommt es dann zu Verlusten von Daten oder Funktionen der alten Version von Analytics?<\/span><\/p>\n<p><span style=\"color: #339966;\">A: Der Website-Besitzer h\u00e4tte die GA3- und GA4-Systeme parallel auf der Website implementiert und jederzeit Zugriff auf beide Produkte. Es best\u00fcnde keine Gefahr, dass Daten verloren gehen.<\/span><\/p>\n<p><strong>Wird es Sie viel kosten?<\/strong><\/p>\n<p><span style=\"color: #ff0000;\">F: Entstehen bei der Erstellung eines GA4-Kontos finanzielle Kosten f\u00fcr den KG Media-Kunden? Erfordert dieser Prozess die Einbindung eines oder mehrerer externer Partner des Kunden (z. B. des Webmasters des Kunden usw.)?<\/span><\/p>\n<p><span style=\"color: #339966;\">A: KG Media-Kunden, die unseren Google Tag Manager (GTM) auf der Website eingerichtet haben \u2013 und das ist die \u00fcberwiegende Mehrheit \u2013 m\u00fcssen keine Webmaster oder andere externe Partner beauftragen.<\/span><\/p>\n<p><strong>Wann funktioniert die aktuelle Version von Analytics nicht mehr?<\/strong><\/p>\n<p><span style=\"color: #ff0000;\">F: Gibt es Informationen dar\u00fcber, wann Google voraussichtlich eine &#8222;erzwungene&#8220; Umstellung auf GA4 vornehmen wird und was erwarten wir: Wie w\u00fcrde diese \u00c4nderung aussehen?<\/span><\/p>\n<p><span style=\"color: #339966;\">A: Google schl\u00e4gt vorerst vor, beide Produkte parallel zu verwenden. Wir haben keine Informationen dar\u00fcber, wann Google plant, GA3 vollst\u00e4ndig einzustellen, aber da Cookies im Laufe der Zeit verschwinden und Browser im Laufe der Zeit immer mehr Blockaden aufweisen, wird GA3 immer weniger zuverl\u00e4ssig und genau sein.<\/span><\/p>\n<p><span style=\"color: #339966;\">Auch bei der Er\u00f6ffnung neuer Konten f\u00fcr GA3 (Universal Analytics) wird empfohlen, sowohl GA3 als auch GA4 zu erstellen &#x1f449; siehe Bild unten:<\/span><\/p>\n<figure id=\"attachment_4961\" aria-describedby=\"caption-attachment-4961\" style=\"width: 777px\" class=\"wp-caption aligncenter\"><a ref=\"magnificPopup\" href=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/1.png\" class=\"fancybox\" ><img decoding=\"async\" class=\"wp-image-4961 size-full\" title=\"Google schl\u00e4gt vor, sowohl Universal Analytics- als auch Google Analytics 4-Benutzerkonten f\u00fcr die parallele Nutzung zu er\u00f6ffnen.\" src=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/1.png\" alt=\"GA3 &amp; GA4\" width=\"777\" height=\"264\" srcset=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/1.png 777w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/1-300x102.png 300w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/1-768x261.png 768w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/1-250x85.png 250w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/1-400x136.png 400w\" sizes=\"(max-width: 777px) 100vw, 777px\" \/><\/a><figcaption id=\"caption-attachment-4961\" class=\"wp-caption-text\">Google schl\u00e4gt vor, sowohl Universal Analytics- als auch Google Analytics 4-Benutzerkonten f\u00fcr die parallele Nutzung zu er\u00f6ffnen.<\/figcaption><\/figure>\n<p><strong>Was bedeutet das f\u00fcr KGM?<\/strong><\/p>\n<p><span style=\"color: #ff0000;\">F: Was w\u00fcrde die Implementierung von GA4 auf Kunden-Websites f\u00fcr KG Media \u00e4ndern? Was sind die Vorteile und was sind die m\u00f6glichen Nachteile?<\/span><\/p>\n<p><span style=\"color: #339966;\">A: Der Vorteil ist, dass wir in ein paar Jahren, wenn GA3 verschwindet, nicht bei Null anfangen m\u00fcssen, sondern Datenbanken aufgebaut haben, die wir dann f\u00fcr die Kampagnen unserer Kunden, Beratungsdienste und andere Zwecke verwenden k\u00f6nnen. Es gibt keine Nachteile.<\/span><\/p>\n<p><span style=\"color: #339966;\">Z.B. RiverSide Garden<\/span> &#x1f449; <a href=\"https:\/\/riversidegarden.hr\/\">https:\/\/riversidegarden.hr\/<\/a> <span style=\"color: #339966;\">hat GA4 bereits auf seiner Website installiert.<\/span><\/p>\n<p><strong>Wie funktioniert Retargeting mit Google Analytics 4?<\/strong><\/p>\n<p><span style=\"color: #ff0000;\">F: Wenn GA4 nicht auf Basis von Cookies, sondern auf Basis von Tracking-Ereignissen auf der Seite funktioniert, wie funktioniert dann Remarketing?<\/span><\/p>\n<p><span style=\"color: #339966;\">A: GA4 funktioniert auf Basis von<\/span> <a href=\"https:\/\/de.wikipedia.org\/wiki\/HTTP-Cookie\">First-Party-Cookies<\/a><span style=\"color: #339966;\">, soll aber in Zukunft auch ohne funktionieren.<\/span><\/p>\n<p><span style=\"color: #339966;\">Das sagt Google:<\/span><\/p>\n<p><span style=\"color: #339966;\"><em>\u00a0\u00a0\u00a0 \u201eDa sich die Technologielandschaft st\u00e4ndig weiterentwickelt, ist das neue Analytics darauf ausgelegt, sich mit oder ohne Cookies oder Identifikatoren an eine Zukunft anzupassen. Es verwendet einen flexiblen Messansatz und wird in Zukunft Modellierungen beinhalten, um L\u00fccken zu schlie\u00dfen, in denen die Daten m\u00f6glicherweise unvollst\u00e4ndig sind. Das bedeutet, dass Sie sich auf Google Analytics verlassen k\u00f6nnen, um Ihre Marketingergebnisse zu messen und die Kundenbed\u00fcrfnisse jetzt zu erf\u00fcllen, w\u00e4hrend Sie die Erholung navigieren und in Zukunft mit Unsicherheit konfrontiert sind. \u201d<\/em><\/span><\/p>\n<p><strong>Wenn es keine Cookies verwendet, was verwendet es dann?<\/strong><\/p>\n<p><span style=\"color: #ff0000;\">F: Nach welchem \u200b\u200bPrinzip erkennt GA4, dass es derselbe Benutzer ist, der von verschiedenen Ger\u00e4ten auf das Web \u2013 wo GA4 installiert ist \u2013 zugreift, wenn keine Cookies verwendet werden?<\/span><\/p>\n<p><span style=\"color: #339966;\">A: Lassen Sie uns zun\u00e4chst die Terminologie zu diesem Thema kl\u00e4ren:<\/span><\/p>\n<ul>\n<li><span style=\"color: #339966;\"><strong>Client-ID<\/strong> \u2013 verfolgt Benutzer \u00fcber Cookies und Ger\u00e4te-ID &#8211; daher ist eine ger\u00e4te\u00fcbergreifende Nutzung nicht m\u00f6glich;<\/span><\/li>\n<li><span style=\"color: #339966;\"><strong>Benutzer-ID<\/strong> \u2013 Nachverfolgung von Benutzern, die sich im Web und der Anwendung und ger\u00e4te\u00fcbergreifend anmelden. Ist nur m\u00f6glich, wenn sich Benutzer zuvor bei ihrem Google-Konto angemeldet haben;<\/span><\/li>\n<li><span style=\"color: #339966;\"><strong>Google Signals<\/strong> \u2013 \u201everfolgt\u201c Benutzer, die sich bei einem Google-Konto anmelden.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #339966;\">In Google Analytics 3 funktionierten Benutzer-ID, Client-ID und Google-Signals separat und jedes hat seine &#8222;Berichte&#8220;. Innerhalb von Google Analytics 4 sind sie verbunden.<\/span><\/p>\n<p><span style=\"color: #339966;\">Versuchen wir, dies visuell zu verdeutlichen:<\/span><\/p>\n<h4>Google Analytics 3:<\/h4>\n<p style=\"text-align: left;\"><a ref=\"magnificPopup\" href=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA3_.png\" class=\"fancybox\" ><img decoding=\"async\" width=\"300\" height=\"222\" class=\"size-medium wp-image-4897 alignleft\" src=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA3_-300x222.png\" alt=\"\" srcset=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA3_-300x222.png 300w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA3_-115x85.png 115w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA3_-338x250.png 338w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA3_.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<h4>Google Analytics 4:<\/h4>\n<p><a ref=\"magnificPopup\" href=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4_.png\" class=\"fancybox\" ><img decoding=\"async\" class=\"alignleft wp-image-4894 size-medium\" src=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4_-300x300.png\" alt=\"GA4\" width=\"300\" height=\"300\" srcset=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4_-300x300.png 300w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4_-150x150.png 150w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4_-85x85.png 85w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4_-250x250.png 250w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4_.png 494w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><span style=\"color: #ff0000;\">F: Wer bestimmt, was alles in GA4 auf der Website des Kunden als Ereignis festgelegt werden soll? Wie kann das potenzielle Problem vermieden werden, Ereignisse auf der Website zu definieren, die dann in GA4 nachverfolgt w\u00fcrden und die f\u00fcr den Websitebesitzer keine Bedeutung haben?<\/span><\/p>\n<p><span style=\"color: #339966;\">A: Bei der Einrichtung von GA4 f\u00fcr seine Kunden beginnt KG Media mit der \u00dcberwachung aller sogenannten <strong>verbesserten Messereignisse<\/strong> + Ereignisse \/ Ziele, auf die wir uns zus\u00e4tzlich einigen w\u00fcrden.<\/span><\/p>\n<p><span style=\"color: #339966;\">Verbesserte Messereignisse sind:<\/span><\/p>\n<figure id=\"attachment_4965\" aria-describedby=\"caption-attachment-4965\" style=\"width: 523px\" class=\"wp-caption aligncenter\"><a ref=\"magnificPopup\" href=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/2.png\" class=\"fancybox\" ><img decoding=\"async\" class=\"wp-image-4965 size-full\" title=\"Verbesserte Messereignisse in GA4\" src=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/2.png\" alt=\"Verbesserte Messereignisse in GA4\" width=\"523\" height=\"516\" srcset=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/2.png 523w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/2-300x296.png 300w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/2-86x85.png 86w, https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/10\/2-253x250.png 253w\" sizes=\"(max-width: 523px) 100vw, 523px\" \/><\/a><figcaption id=\"caption-attachment-4965\" class=\"wp-caption-text\">Verbesserte Messereignisse in GA4<\/figcaption><\/figure>\n<p><span style=\"color: #ff0000;\">F: Wird GA4 mit Google Data Studio so kompatibel sein, dass die Implementierung von Google Analytics 4 beginnt, Informationen an die GDS-Schnittstelle zu senden, in der die Daten von GA3 erg\u00e4nzt werden?<\/span><\/p>\n<p><span style=\"color: #339966;\">A: Ja. Wir m\u00fcssen nat\u00fcrlich DataStudio mit GA4 verbinden und anpassen, damit Teile des Berichts von GA4 auch in Google Data Studio nachverfolgt werden k\u00f6nnen.<\/span><\/p>\n \n\t\t<button id=\"btn_contact_form\" class=\"btn btn-primary btn-lg btn--cta \" type=\"button\" data-toggle=\"modal\" data-target=\"#cfModal\">Kontaktieren Sie uns!<span style=\"font-weight: 400;\"><\/button>\n<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google Analytics 4 (GA4) ist eine neue Generation von Google Analytics. Lesen Sie, warum Sie es auf Ihrer Website implementieren m\u00fcssen.<\/p>\n","protected":false},"author":11,"featured_media":4911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[723,118],"class_list":["post-4946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-ga4","tag-google-analytics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GA4: Google Analytics 4 ist da! Was Sie dar\u00fcber wissen m\u00fcssen<\/title>\n<meta name=\"description\" content=\"Google Analytics 4 (GA4) ist eine neue Generation von Google Analytics. Lesen Sie, warum Sie es auf Ihrer Website implementieren m\u00fcssen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GA4 - Google Analytics 4 ist da\" \/>\n<meta property=\"og:description\" content=\"Google Analytics 4 (GA4) ist eine neue Generation von Google Analytics. Lesen Sie, warum Sie es auf Ihrer Website implementieren m\u00fcssen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/\" \/>\n<meta property=\"og:site_name\" content=\"KG Media\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kgmedia.agencija\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/aldic.filip\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-21T07:05:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T10:21:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"604\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Filip Aldi\u0107\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/\"},\"author\":{\"name\":\"Filip Aldi\u0107\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#\\\/schema\\\/person\\\/fbc79859a9fef76ae9fb6a98419ae479\"},\"headline\":\"GA4 &#8211; Google Analytics 4 ist da\",\"datePublished\":\"2021-10-21T07:05:42+00:00\",\"dateModified\":\"2025-03-07T10:21:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/\"},\"wordCount\":1474,\"publisher\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/GA4-.png\",\"keywords\":[\"ga4\",\"google analytics\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/\",\"name\":\"GA4: Google Analytics 4 ist da! Was Sie dar\u00fcber wissen m\u00fcssen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/GA4-.png\",\"datePublished\":\"2021-10-21T07:05:42+00:00\",\"dateModified\":\"2025-03-07T10:21:08+00:00\",\"description\":\"Google Analytics 4 (GA4) ist eine neue Generation von Google Analytics. Lesen Sie, warum Sie es auf Ihrer Website implementieren m\u00fcssen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/GA4-.png\",\"contentUrl\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/GA4-.png\",\"width\":604,\"height\":526,\"caption\":\"GA4\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/ga4-google-analytics-4-ist-da\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GA4 &#8211; Google Analytics 4 ist da\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/\",\"name\":\"KG Media\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#organization\",\"name\":\"KG Media\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/kgm-logo.png\",\"contentUrl\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/kgm-logo.png\",\"width\":220,\"height\":154,\"caption\":\"KG Media\"},\"image\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kgmedia.agencija\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kg-media\\\/\",\"https:\\\/\\\/www.instagram.com\\\/kgmedia.agencija\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#\\\/schema\\\/person\\\/fbc79859a9fef76ae9fb6a98419ae479\",\"name\":\"Filip Aldi\u0107\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/filip-aldic-96x96.jpg\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/filip-aldic-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/filip-aldic-96x96.jpg\",\"caption\":\"Filip Aldi\u0107\"},\"description\":\"Filip je magistar in\u017eenjer medijskih komunikacija (mag. in\u017e. med. kom.). U KG Mediji je zadu\u017een za postavljanje tracking usluga na va\u0161im stranicama.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aldic.filip\"],\"url\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/author\\\/fialdic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GA4: Google Analytics 4 ist da! Was Sie dar\u00fcber wissen m\u00fcssen","description":"Google Analytics 4 (GA4) ist eine neue Generation von Google Analytics. Lesen Sie, warum Sie es auf Ihrer Website implementieren m\u00fcssen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/","og_locale":"de_DE","og_type":"article","og_title":"GA4 - Google Analytics 4 ist da","og_description":"Google Analytics 4 (GA4) ist eine neue Generation von Google Analytics. Lesen Sie, warum Sie es auf Ihrer Website implementieren m\u00fcssen.","og_url":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/","og_site_name":"KG Media","article_publisher":"https:\/\/www.facebook.com\/kgmedia.agencija\/","article_author":"https:\/\/www.facebook.com\/aldic.filip","article_published_time":"2021-10-21T07:05:42+00:00","article_modified_time":"2025-03-07T10:21:08+00:00","og_image":[{"width":604,"height":526,"url":"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4-.png","type":"image\/png"}],"author":"Filip Aldi\u0107","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/#article","isPartOf":{"@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/"},"author":{"name":"Filip Aldi\u0107","@id":"https:\/\/kg-media.eu\/de\/#\/schema\/person\/fbc79859a9fef76ae9fb6a98419ae479"},"headline":"GA4 &#8211; Google Analytics 4 ist da","datePublished":"2021-10-21T07:05:42+00:00","dateModified":"2025-03-07T10:21:08+00:00","mainEntityOfPage":{"@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/"},"wordCount":1474,"publisher":{"@id":"https:\/\/kg-media.eu\/de\/#organization"},"image":{"@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/#primaryimage"},"thumbnailUrl":"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4-.png","keywords":["ga4","google analytics"],"articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/","url":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/","name":"GA4: Google Analytics 4 ist da! Was Sie dar\u00fcber wissen m\u00fcssen","isPartOf":{"@id":"https:\/\/kg-media.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/#primaryimage"},"image":{"@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/#primaryimage"},"thumbnailUrl":"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4-.png","datePublished":"2021-10-21T07:05:42+00:00","dateModified":"2025-03-07T10:21:08+00:00","description":"Google Analytics 4 (GA4) ist eine neue Generation von Google Analytics. Lesen Sie, warum Sie es auf Ihrer Website implementieren m\u00fcssen.","breadcrumb":{"@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/#primaryimage","url":"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4-.png","contentUrl":"https:\/\/kg-media.eu\/wp-content\/uploads\/2021\/09\/GA4-.png","width":604,"height":526,"caption":"GA4"},{"@type":"BreadcrumbList","@id":"https:\/\/kg-media.eu\/de\/blog\/ga4-google-analytics-4-ist-da\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kg-media.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/kg-media.eu\/de\/blog\/"},{"@type":"ListItem","position":3,"name":"GA4 &#8211; Google Analytics 4 ist da"}]},{"@type":"WebSite","@id":"https:\/\/kg-media.eu\/de\/#website","url":"https:\/\/kg-media.eu\/de\/","name":"KG Media","description":"","publisher":{"@id":"https:\/\/kg-media.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kg-media.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/kg-media.eu\/de\/#organization","name":"KG Media","url":"https:\/\/kg-media.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kg-media.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/kg-media.eu\/wp-content\/uploads\/2024\/06\/kgm-logo.png","contentUrl":"https:\/\/kg-media.eu\/wp-content\/uploads\/2024\/06\/kgm-logo.png","width":220,"height":154,"caption":"KG Media"},"image":{"@id":"https:\/\/kg-media.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kgmedia.agencija\/","https:\/\/www.linkedin.com\/company\/kg-media\/","https:\/\/www.instagram.com\/kgmedia.agencija\/"]},{"@type":"Person","@id":"https:\/\/kg-media.eu\/de\/#\/schema\/person\/fbc79859a9fef76ae9fb6a98419ae479","name":"Filip Aldi\u0107","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kg-media.eu\/wp-content\/uploads\/2017\/04\/filip-aldic-96x96.jpg","url":"https:\/\/kg-media.eu\/wp-content\/uploads\/2017\/04\/filip-aldic-96x96.jpg","contentUrl":"https:\/\/kg-media.eu\/wp-content\/uploads\/2017\/04\/filip-aldic-96x96.jpg","caption":"Filip Aldi\u0107"},"description":"Filip je magistar in\u017eenjer medijskih komunikacija (mag. in\u017e. med. kom.). U KG Mediji je zadu\u017een za postavljanje tracking usluga na va\u0161im stranicama.","sameAs":["https:\/\/www.facebook.com\/aldic.filip"],"url":"https:\/\/kg-media.eu\/de\/author\/fialdic\/"}]}},"_links":{"self":[{"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/posts\/4946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/comments?post=4946"}],"version-history":[{"count":0,"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/posts\/4946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/media\/4911"}],"wp:attachment":[{"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/media?parent=4946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/categories?post=4946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/tags?post=4946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}