{"id":2749,"date":"2018-05-03T07:48:25","date_gmt":"2018-05-03T07:48:25","guid":{"rendered":"https:\/\/kg-media.eu\/?page_id=2749"},"modified":"2025-04-10T08:33:39","modified_gmt":"2025-04-10T06:33:39","slug":"ceeda","status":"publish","type":"page","link":"https:\/\/kg-media.eu\/de\/ceeda\/","title":{"rendered":"CEEDA"},"content":{"rendered":"<p>Sprechen Sie lokal in allen CEE Regionen.<\/p>\n<p>\u00dcberlassen Sie marktspezifische Jobs CEEdigitalAlliance-Cluster-Mitgliedern, die am jeweiligen Markt zuhause sind.<\/p>\n<p>Erreichen Sie Ihre Zielgruppe bestm\u00f6glich in Kroatien, Tschechien, Polen, Ungarn, Litauen, Rum\u00e4nien, der Slowakei und der Ukraine.<\/p>\n<p>Sie sprechen die Sprache, kennen den Kontext.<\/p>\n<p>Ernten Sie beste Ergebnisse.<\/p>\n<p>Jede Agentur im CEEdigitalAlliance-Netzwerk ist ein Google Premier-Partner, qualifiziert und erfahren in den Bereichen Digitale Analytics, SEO-Optimierung, PPC, Display und Social Network Werbung. \u00a0<\/p>\n<h2><strong>Ein Haufen von Experten:<\/strong><\/h2>\n<ol>\n<li>Croatia &#8211; <strong>KG Media<\/strong><\/li>\n<li>Austria &#8211; <strong>KG Media<\/strong><\/li>\n<li>Romania &#8211; <a href=\"https:\/\/webdigital.ro\/\" target=\"_blank\" rel=\"noopener\">WebDigital<\/a> and <a href=\"https:\/\/dwf.ro\/\" target=\"_blank\" rel=\"noopener\">DWF<\/a><\/li>\n<li>Bulgaria &#8211; <a href=\"https:\/\/netpeak.bg\/\" target=\"_blank\" rel=\"noopener\">Netpeak<\/a><\/li>\n<li>Ukraine &#8211; <a href=\"https:\/\/netpeak.bg\/\" target=\"_blank\" rel=\"noopener\">Netpeak<\/a> and <a href=\"https:\/\/www.promodo.com\/\" target=\"_blank\" rel=\"noopener\">Promodo<\/a><\/li>\n<li>Greece &#8211; <a href=\"https:\/\/www.omnicliq.com\/en\/\" target=\"_blank\" rel=\"noopener\">Omnicliq<\/a><\/li>\n<li>Hungary &#8211; <a href=\"https:\/\/www.growwwdigital.com\/\" target=\"_blank\" rel=\"noopener\">Growww Digital<\/a> and <a href=\"https:\/\/intren.digital\/\" target=\"_blank\" rel=\"noopener\">Intren<\/a><\/li>\n<li>Slovenia &#8211; <a href=\"https:\/\/www.dinetix.com\/\" target=\"_blank\" rel=\"noopener\">Dinetix<\/a> and <a href=\"https:\/\/www.kokos.agency\/en\" target=\"_blank\" rel=\"noopener\">Kokos<\/a><\/li>\n<li>Slovakia &#8211; <a href=\"https:\/\/bastadigital.com\/en\/\" target=\"_blank\" rel=\"noopener\">Basta Digital<\/a> and <a href=\"https:\/\/www.promiseo.com\/\" target=\"_blank\" rel=\"noopener\">Promiseo<\/a><\/li>\n<li>Czech Republic &#8211; <a href=\"https:\/\/www.effectix.com\/en\/\" target=\"_blank\" rel=\"noopener\">Effectix<\/a> and <a href=\"https:\/\/www.fragile.cz\/eng\/\" target=\"_blank\" rel=\"noopener\">Fragile Media<\/a><\/li>\n<li>Poland &#8211; <a href=\"https:\/\/www.bluerank.com\/en\/\" target=\"_blank\" rel=\"noopener\">Bluerank<\/a><\/li>\n<li>Lithuania &#8211; <a href=\"https:\/\/mbd.lt\/en\/\" target=\"_blank\" rel=\"noopener\">MBD.<\/a><\/li>\n<li>Estonia &#8211; <a href=\"https:\/\/mbd.lt\/en\/\" target=\"_blank\" rel=\"noopener\">MBD.<\/a><\/li>\n<li>Latvia &#8211; <a href=\"https:\/\/mbd.lt\/en\/\" target=\"_blank\" rel=\"noopener\">MBD.<\/a><\/li>\n<\/ol>\n<p>Um das regionale Know-how und die lokale Markterfahrung zu teilen, erm\u00f6glicht uns BlueAlliance, das Gesamtbild zu sehen und bessere Einblicke innerhalb der CEE-Region zu erhalten.<\/p>\n<h2><strong>BlueAlliance verbindet :<\/strong><\/h2>\n<ul>\n<li>\u00a01209 Zertifikate<\/li>\n<li>\u00a0751 Mitarbeiter<\/li>\n<li>\u00a03897 Projekte<\/li>\n<li>\u00a076 Preise<\/li>\n<li>\u00a0mehr als 108 Millionen \u20ac Werbeetat<\/li>\n<\/ul>\n<p><a href=\"https:\/\/ceedigitalalliance.com\/\" target=\"_blank\" rel=\"noopener\">United we click<\/a><\/p>\n<p>#CEEdigitalAlliance #CEEPremierPartnersAlliance<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sprechen Sie lokal in allen CEE Regionen. \u00dcberlassen Sie marktspezifische Jobs CEEdigitalAlliance-Cluster-Mitgliedern, die am jeweiligen Markt zuhause sind. Erreichen Sie Ihre Zielgruppe bestm\u00f6glich in Kroatien, Tschechien, Polen, Ungarn, Litauen, Rum\u00e4nien, der Slowakei und der Ukraine. Sie sprechen die Sprache, kennen den Kontext. Ernten Sie beste Ergebnisse. Jede Agentur im CEEdigitalAlliance-Netzwerk ist ein Google Premier-Partner, qualifiziert&#8230;<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2749","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>KG Media ist Mitglied der CEEdigitalAlliance Gruppe. Profitieren Sie davon!<\/title>\n<meta name=\"description\" content=\"CEEDA bringt Wissen und Erfahrung von 13 lokalen Agenturen zusammen. Das bietet bessere Leistung und Einblicke in die jeweiligen Heimatm\u00e4rkte innerhalb der CEE-Region. Erreichen Sie z.B. den kroatischen, tschechischen, polnischen Markt mit lokalem Know-how f\u00fcr beste Ergebnisse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kg-media.eu\/de\/ceeda\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEEDA\" \/>\n<meta property=\"og:description\" content=\"CEEDA bringt Wissen und Erfahrung von 13 lokalen Agenturen zusammen. Das bietet bessere Leistung und Einblicke in die jeweiligen Heimatm\u00e4rkte innerhalb der CEE-Region. Erreichen Sie z.B. den kroatischen, tschechischen, polnischen Markt mit lokalem Know-how f\u00fcr beste Ergebnisse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kg-media.eu\/de\/ceeda\/\" \/>\n<meta property=\"og:site_name\" content=\"KG Media\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kgmedia.agencija\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T06:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kg-media.eu\/wp-content\/uploads\/2016\/12\/kgm-fb-default.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"605\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/ceeda\\\/\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/ceeda\\\/\",\"name\":\"KG Media ist Mitglied der CEEdigitalAlliance Gruppe. Profitieren Sie davon!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#website\"},\"datePublished\":\"2018-05-03T07:48:25+00:00\",\"dateModified\":\"2025-04-10T06:33:39+00:00\",\"description\":\"CEEDA bringt Wissen und Erfahrung von 13 lokalen Agenturen zusammen. Das bietet bessere Leistung und Einblicke in die jeweiligen Heimatm\u00e4rkte innerhalb der CEE-Region. Erreichen Sie z.B. den kroatischen, tschechischen, polnischen Markt mit lokalem Know-how f\u00fcr beste Ergebnisse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/ceeda\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kg-media.eu\\\/de\\\/ceeda\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/ceeda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CEEDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/\",\"name\":\"KG Media\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#organization\",\"name\":\"KG Media\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/kgm-logo.png\",\"contentUrl\":\"https:\\\/\\\/kg-media.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/kgm-logo.png\",\"width\":220,\"height\":154,\"caption\":\"KG Media\"},\"image\":{\"@id\":\"https:\\\/\\\/kg-media.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kgmedia.agencija\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kg-media\\\/\",\"https:\\\/\\\/www.instagram.com\\\/kgmedia.agencija\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"KG Media ist Mitglied der CEEdigitalAlliance Gruppe. Profitieren Sie davon!","description":"CEEDA bringt Wissen und Erfahrung von 13 lokalen Agenturen zusammen. Das bietet bessere Leistung und Einblicke in die jeweiligen Heimatm\u00e4rkte innerhalb der CEE-Region. Erreichen Sie z.B. den kroatischen, tschechischen, polnischen Markt mit lokalem Know-how f\u00fcr beste Ergebnisse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kg-media.eu\/de\/ceeda\/","og_locale":"de_DE","og_type":"article","og_title":"CEEDA","og_description":"CEEDA bringt Wissen und Erfahrung von 13 lokalen Agenturen zusammen. Das bietet bessere Leistung und Einblicke in die jeweiligen Heimatm\u00e4rkte innerhalb der CEE-Region. Erreichen Sie z.B. den kroatischen, tschechischen, polnischen Markt mit lokalem Know-how f\u00fcr beste Ergebnisse.","og_url":"https:\/\/kg-media.eu\/de\/ceeda\/","og_site_name":"KG Media","article_publisher":"https:\/\/www.facebook.com\/kgmedia.agencija\/","article_modified_time":"2025-04-10T06:33:39+00:00","og_image":[{"width":605,"height":317,"url":"https:\/\/kg-media.eu\/wp-content\/uploads\/2016\/12\/kgm-fb-default.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kg-media.eu\/de\/ceeda\/","url":"https:\/\/kg-media.eu\/de\/ceeda\/","name":"KG Media ist Mitglied der CEEdigitalAlliance Gruppe. Profitieren Sie davon!","isPartOf":{"@id":"https:\/\/kg-media.eu\/de\/#website"},"datePublished":"2018-05-03T07:48:25+00:00","dateModified":"2025-04-10T06:33:39+00:00","description":"CEEDA bringt Wissen und Erfahrung von 13 lokalen Agenturen zusammen. Das bietet bessere Leistung und Einblicke in die jeweiligen Heimatm\u00e4rkte innerhalb der CEE-Region. Erreichen Sie z.B. den kroatischen, tschechischen, polnischen Markt mit lokalem Know-how f\u00fcr beste Ergebnisse.","breadcrumb":{"@id":"https:\/\/kg-media.eu\/de\/ceeda\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kg-media.eu\/de\/ceeda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kg-media.eu\/de\/ceeda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kg-media.eu\/de\/"},{"@type":"ListItem","position":2,"name":"CEEDA"}]},{"@type":"WebSite","@id":"https:\/\/kg-media.eu\/de\/#website","url":"https:\/\/kg-media.eu\/de\/","name":"KG Media","description":"","publisher":{"@id":"https:\/\/kg-media.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kg-media.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/kg-media.eu\/de\/#organization","name":"KG Media","url":"https:\/\/kg-media.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kg-media.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/kg-media.eu\/wp-content\/uploads\/2024\/06\/kgm-logo.png","contentUrl":"https:\/\/kg-media.eu\/wp-content\/uploads\/2024\/06\/kgm-logo.png","width":220,"height":154,"caption":"KG Media"},"image":{"@id":"https:\/\/kg-media.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kgmedia.agencija\/","https:\/\/www.linkedin.com\/company\/kg-media\/","https:\/\/www.instagram.com\/kgmedia.agencija\/"]}]}},"_links":{"self":[{"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/pages\/2749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/comments?post=2749"}],"version-history":[{"count":0,"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/pages\/2749\/revisions"}],"wp:attachment":[{"href":"https:\/\/kg-media.eu\/de\/wp-json\/wp\/v2\/media?parent=2749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}